{"id":60,"count":3750,"description":"<div>Bitcoin es una criptomoneda creada en 2009 por un desconocido con el nombre de Satoshi Nakamoto. Se trata de una moneda digital descentralizada, sin banco central ni administrador \u00fanico, que puede enviarse de usuario a usuario en la red peer-to-peer Bitcoin sin necesidad de intermediarios. Las transacciones son verificadas por los nodos de la red mediante criptograf\u00eda y registradas en un libro de contabilidad de distribuci\u00f3n p\u00fablica denominado blockchain.<\/div>","link":"https:\/\/crypto-economy.com\/es\/tag\/bitcoin\/","name":"bitcoin","slug":"bitcoin","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/tags\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts?tags=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}