{"id":78635,"date":"2024-02-08T14:25:02","date_gmt":"2024-02-08T14:25:02","guid":{"rendered":"https:\/\/crypto-economy.com\/es\/?p=78635"},"modified":"2024-02-08T14:25:38","modified_gmt":"2024-02-08T14:25:38","slug":"la-red-social-descentralizada-de-jack-dorsey-bluesky-alcanza-1-millon-de-nuevos-usuarios-en-tan-solo-24-horas-despues-de-su-lanzamiento-publico","status":"publish","type":"post","link":"https:\/\/crypto-economy.com\/es\/la-red-social-descentralizada-de-jack-dorsey-bluesky-alcanza-1-millon-de-nuevos-usuarios-en-tan-solo-24-horas-despues-de-su-lanzamiento-publico\/","title":{"rendered":"La Red Social Descentralizada de Jack Dorsey, Bluesky, Alcanza 1 Mill\u00f3n de Nuevos Usuarios en Tan Solo 24 Horas Despu\u00e9s de su Lanzamiento P\u00fablico"},"content":{"rendered":"<p>Puntos clave de la noticia:<\/p>\n<ul>\n<li style=\"text-align: justify\">Bluesky experiment\u00f3 un r\u00e1pido crecimiento desde su lanzamiento p\u00fablico, atrayendo a <strong>m\u00e1s de 1 mill\u00f3n de nuevos usuarios en solo 24 horas<\/strong> y superando los 4 millones de registros en total.<\/li>\n<li style=\"text-align: justify\">Las plataformas descentralizadas <strong>est\u00e1n ganando terreno como alternativas a los gigantes centralizados<\/strong> como Meta.<\/li>\n<li style=\"text-align: justify\">Aunque <strong>enfrent\u00f3 desaf\u00edos t\u00e9cnicos despu\u00e9s de su lanzamiento<\/strong>, como interrupciones en sus feeds algor\u00edtmicos personalizados, Bluesky trabaj\u00f3 para <strong>resolver los problemas y restablecer el servicio<\/strong>.<br \/>\n<hr \/>\n<\/li>\n<\/ul>\n<p style=\"text-align: justify\"><strong>Bluesky, la red social descentralizada respaldada por Jack Dorsey, experiment\u00f3 un notable crecimiento desde su <a href=\"https:\/\/crypto-economy.com\/es\/bluesky-la-red-social-descentralizada-de-jack-dorsey-ahora-esta-abierta-a-todos-los-usuarios\/\" target=\"_blank\" rel=\"noopener\">lanzamiento<\/a> p\u00fablico, atrayendo a m\u00e1s de 1,000,000 de usuarios nuevos en tan solo 24 horas<\/strong>. Este incremento en su base de usuarios llev\u00f3 a la plataforma a superar los 4 millones de registros en total. Anteriormente, <strong>Bluesky requer\u00eda un c\u00f3digo de invitaci\u00f3n para acceder, pero recientemente anunci\u00f3 que ahora est\u00e1 abierta para todos, sin necesidad de invitaciones.<\/strong><!--more--><\/p>\n<p style=\"text-align: justify\">El r\u00e1pido crecimiento de Bluesky refleja un cambio en el futuro de las redes sociales, donde plataformas <a href=\"https:\/\/crypto-economy.com\/es\/defi-finanzas-descentralizadas\/\" target=\"_blank\" rel=\"noopener\">descentralizadas<\/a> como esta <strong>est\u00e1n ganando terreno como alternativas a los gigantes centralizados como Meta<\/strong> (anteriormente conocida como Facebook). Aunque a\u00fan se encuentra por detr\u00e1s de su competidor principal, <strong>Mastodon, que logr\u00f3 un crecimiento a\u00fan mayor desde que Twitter cambi\u00f3 de propiedad.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Welcome to the 1M+ new users who joined Bluesky since we opened access yesterday!<\/p>\n<p>Sign up here: <a href=\"https:\/\/t.co\/exCdOOYprz\">https:\/\/t.co\/exCdOOYprz<\/a> <a href=\"https:\/\/t.co\/si9dn04zp2\">pic.twitter.com\/si9dn04zp2<\/a><\/p>\n<p>&mdash; bluesky (@bluesky) <a href=\"https:\/\/twitter.com\/bluesky\/status\/1755468956893434231?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">February 8, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Bluesky Sufri\u00f3 Una Sobrecarga en su Base de Datos, Afectando el Feed de los Usuarios<\/h2>\n<p style=\"text-align: justify\">Sin embargo, el camino hacia el \u00e9xito no estuvo exento de desaf\u00edos para Bluesky. Tras su lanzamiento p\u00fablico, <strong>la <a href=\"https:\/\/bsky.social\/about\" target=\"_blank\" rel=\"noopener\">plataforma<\/a> enfrent\u00f3 problemas t\u00e9cnicos con sus feeds algor\u00edtmicos personalizados<\/strong>, lo que provoc\u00f3 <strong>una interrupci\u00f3n temporal en el servicio<\/strong>. El equipo t\u00e9cnico de la red social trabaj\u00f3 arduamente para solucionar estos problemas y, en poco tiempo, la aplicaci\u00f3n <strong>volvi\u00f3 a funcionar con normalidad<\/strong>. Paul Frazee, un miembro del equipo t\u00e9cnico, explic\u00f3 que<strong> el problema se debi\u00f3 a un aumento repentino en el uso de la base de datos, lo que provoc\u00f3 una sobrecarga en el sistema<\/strong>.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-78640\" src=\"https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2024\/02\/bluesky-post-1.jpg\" alt=\"bluesky post\" width=\"825\" height=\"300\" srcset=\"https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2024\/02\/bluesky-post-1.jpg 825w, https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2024\/02\/bluesky-post-1-300x109.jpg 300w, https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2024\/02\/bluesky-post-1-768x279.jpg 768w\" sizes=\"(max-width: 825px) 100vw, 825px\" \/><\/p>\n<p style=\"text-align: justify\">Aunque Bluesky comparte algunas similitudes en apariencia y funcionalidad con Twitter, <strong>se diferencia por su uso del Protocolo AT, que ofrece a los usuarios un mayor control sobre sus interacciones en la plataforma<\/strong>. La intenci\u00f3n subyacente es construir una red social que sea <strong>f\u00e1cil de usar y que permita contribuciones<\/strong> por parte de la comunidad.<\/p>\n<p style=\"text-align: justify\">El respaldo de Jack Dorsey, el cofundador y ex CEO de Twitter, <strong>gener\u00f3 un considerable inter\u00e9s en Bluesky desde sus inicios en 2019<\/strong>. Aunque Dorsey estaba al frente de Twitter cuando comenz\u00f3 a incubar la idea.<\/p>\n<p style=\"text-align: justify\">El \u00e9xito inicial de Bluesky demuestra el creciente inter\u00e9s en las redes sociales descentralizadas y la b\u00fasqueda de alternativas a los gigantes centralizados.<strong> A pesar de los desaf\u00edos t\u00e9cnicos iniciales, la red social su capacidad para atraer a una gran cantidad de usuarios en un corto per\u00edodo de tiempo<\/strong>, y su futuro parece prometedor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puntos clave de la noticia: Bluesky experiment\u00f3 un r\u00e1pido crecimiento desde su lanzamiento p\u00fablico, atrayendo a m\u00e1s de 1 mill\u00f3n de nuevos usuarios en solo 24 horas y superando los 4 millones de registros en total. Las plataformas descentralizadas est\u00e1n ganando terreno como alternativas a los gigantes centralizados como Meta. Aunque enfrent\u00f3 desaf\u00edos t\u00e9cnicos despu\u00e9s &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La Red Social Descentralizada de Jack Dorsey, Bluesky, Alcanza 1 Mill\u00f3n de Nuevos Usuarios en Tan Solo 24 Horas Despu\u00e9s de su Lanzamiento P\u00fablico\" class=\"read-more button\" href=\"https:\/\/crypto-economy.com\/es\/la-red-social-descentralizada-de-jack-dorsey-bluesky-alcanza-1-millon-de-nuevos-usuarios-en-tan-solo-24-horas-despues-de-su-lanzamiento-publico\/#more-78635\" aria-label=\"Leer m\u00e1s sobre La Red Social Descentralizada de Jack Dorsey, Bluesky, Alcanza 1 Mill\u00f3n de Nuevos Usuarios en Tan Solo 24 Horas Despu\u00e9s de su Lanzamiento P\u00fablico\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":34,"featured_media":78642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"","rank_math_description":"Bluesky experiment\u00f3 un notable crecimiento desde su lanzamiento p\u00fablico, atrayendo a m\u00e1s de 1,000,000 de usuarios nuevos en solo 24 horas.","footnotes":""},"categories":[971,4297,915],"tags":[410,176,274],"class_list":["post-78635","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-companias-noticias","category-featured","tag-dapps","tag-tecnologia","tag-twitter"],"_links":{"self":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/78635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/comments?post=78635"}],"version-history":[{"count":1,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/78635\/revisions"}],"predecessor-version":[{"id":78643,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/78635\/revisions\/78643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/media\/78642"}],"wp:attachment":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/media?parent=78635"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/categories?post=78635"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/tags?post=78635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}