{"id":152978,"date":"2026-05-12T23:03:29","date_gmt":"2026-05-12T23:03:29","guid":{"rendered":"https:\/\/crypto-economy.com\/es\/?p=152978"},"modified":"2026-05-12T23:03:31","modified_gmt":"2026-05-12T23:03:31","slug":"la-sombra-de-burry-por-que-el-profeta-mas-temido-del-mercado-sigue-viendo-a-bitcoin-como-el-gran-desastre-anunciado","status":"publish","type":"post","link":"https:\/\/crypto-economy.com\/es\/la-sombra-de-burry-por-que-el-profeta-mas-temido-del-mercado-sigue-viendo-a-bitcoin-como-el-gran-desastre-anunciado\/","title":{"rendered":"La sombra de Burry: Por qu\u00e9 el profeta m\u00e1s temido del mercado sigue viendo a Bitcoin como el gran desastre anunciado"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Cuando el legendario inversor <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> habla, el mercado escucha; no porque siempre acierte, sino porque su historial obliga a cualquier persona seria a, como m\u00ednimo, tomar nota. El hombre que vio la crisis de las <\/span><b>hipotecas subprime<\/b><span style=\"font-weight: 400\"> cuando el resto del mundo bailaba sobre una monta\u00f1a de deuda basura, y que fue inmortalizado por <\/span><b>Christian Bale<\/b><span style=\"font-weight: 400\"> en <\/span><i><span style=\"font-weight: 400\">La Gran Apuesta<\/span><\/i><span style=\"font-weight: 400\">, lleva a\u00f1os se\u00f1alando al <\/span><a href=\"https:\/\/crypto-economy.com\/es\/que-es-bitcoin\/\" target=\"_blank\" rel=\"noopener\"><b>Bitcoin<\/b><\/a><span style=\"font-weight: 400\"> con el mismo dedo acusador que una vez apunt\u00f3 a Wall Street.<\/span><\/p>\n<p><!--more--><\/p>\n<p><span style=\"font-weight: 400\">Hoy, con el <\/span><a href=\"https:\/\/crypto-economy.com\/es\/btc-cae-mas-de-1k-tras-otro-intento-fallido\/\" target=\"_blank\" rel=\"noopener\"><b>Bitcoin cotizando alrededor de los 82.000 d\u00f3lares<\/b><\/a><span style=\"font-weight: 400\">, sus advertencias suenan con una fuerza particular. Y aunque algunos lo tachen de agorero profesional, merece la pena desgranar su argumento porque, si incluso una peque\u00f1a parte de lo que plantea se cumple, las consecuencias no las pagar\u00e1n los maximalistas ac\u00e9rrimos, sino miles de inversores que hoy se sienten a salvo en la supuesta fortaleza del activo digital.<\/span><\/p>\n<h2><b>Michael Burry y su visi\u00f3n extrema sobre Bitcoin<\/b><\/h2>\n<p><span style=\"font-weight: 400\">La postura de <\/span><b>Burry<\/b><span style=\"font-weight: 400\"> sobre <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> puede resumirse en una frase que \u00e9l mismo dej\u00f3 caer cuando la criptomoneda alcanz\u00f3 por primera vez los <\/span><b>100.000 d\u00f3lares<\/b><span style=\"font-weight: 400\"> a finales de 2025: <\/span><i><span style=\"font-weight: 400\">\u201ces lo m\u00e1s rid\u00edculo que existe\u201d<\/span><\/i><span style=\"font-weight: 400\"> y, remat\u00f3 sin piedad, <\/span><i><span style=\"font-weight: 400\">\u201cno vale nada\u201d<\/span><\/i><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Para quien quiera tomarlo como una simple rabieta de alguien que se perdi\u00f3 el tren, conviene recordar que <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> no es un analista cualquiera que ladra desde la barrera. Su capacidad para <a href=\"https:\/\/michaeljburry.substack.com\/p\/short-thoughts-february-2-2026?utm_source=publication-search\" target=\"_blank\" rel=\"noopener\">leer balances<\/a>, detectar fragilidades ocultas y anticipar comportamientos gregarios lo convierte en una especie de aguafiestas sist\u00e9mico con el que conviene dialogar antes que despreciar.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/\/wp-content\/uploads\/2026\/04\/Bitcoins-Institutional-Surge.jpg\" alt=\"Spot ETF\" \/><\/p>\n<p><span style=\"font-weight: 400\">\u00c9l mismo reconoci\u00f3, con cierta autocr\u00edtica, que en 2013 tuvo la oportunidad de comprar <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> cuando un amigo le insisti\u00f3 y que <\/span><i><span style=\"font-weight: 400\">\u201cse durmi\u00f3\u201d<\/span><\/i><span style=\"font-weight: 400\">, perdi\u00e9ndose una revalorizaci\u00f3n estratosf\u00e9rica. Lejos de empujarlo a comprar tarde, esa experiencia parece haber reforzado su convencimiento de que <\/span><b>Bitcoin no es m\u00e1s que la tulipoman\u00eda del siglo XXI<\/b><span style=\"font-weight: 400\">, <\/span><i><span style=\"font-weight: 400\">\u201cincluso peor que un tulip\u00e1n, porque ha hecho posibles tantas actividades criminales\u201d.<\/span><\/i><\/p>\n<h2><b>La \u201cespiral de la muerte\u201d que Michael Burry teme para Bitcoin<\/b><\/h2>\n<p><span style=\"font-weight: 400\">El argumento central de <\/span><b>Burry<\/b><span style=\"font-weight: 400\"> no es original, pero s\u00ed quir\u00fargico. Considera que <\/span><b>Bitcoin carece de valor intr\u00ednseco<\/b><span style=\"font-weight: 400\">, que su precio est\u00e1 sostenido exclusivamente por la expectativa de que alguien m\u00e1s pague por \u00e9l ma\u00f1ana.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Lo que diferencia a <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> es su capacidad para trazar el mecanismo concreto por el que ese castillo de naipes podr\u00eda derrumbarse.<\/span><\/p>\n<p><span style=\"font-weight: 400\">A principios de 2026, detall\u00f3 algo que bautiz\u00f3 como la <\/span><b>\u201cespiral de la muerte\u201d<\/b><span style=\"font-weight: 400\">, un proceso de retroalimentaci\u00f3n negativa que se activar\u00eda si el precio perfora determinados umbrales.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Seg\u00fan su tesis:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">A <\/span><b>70.000 d\u00f3lares<\/b><span style=\"font-weight: 400\">, grandes corporaciones como <\/span><b>Strategy<\/b><span style=\"font-weight: 400\"> \u2014la antigua MicroStrategy\u2014 empezar\u00edan a tener dificultades para refinanciar sus deudas.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">A <\/span><b>60.000 d\u00f3lares<\/b><span style=\"font-weight: 400\">, el estr\u00e9s se agudizar\u00eda hasta forzar ventas masivas que pondr\u00edan en peligro la viabilidad de empresas cargadas de criptoactivos.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">A <\/span><b>50.000 d\u00f3lares<\/b><span style=\"font-weight: 400\">, el desenlace ser\u00eda la bancarrota en cascada de compa\u00f1\u00edas mineras, con un efecto contaminante que \u00e9l denomina <\/span><b>\u201cagujero negro\u201d.<\/b><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Esto no es ciencia ficci\u00f3n. Es una cadena de causalidad empresarial perfectamente plausible en un entorno de apalancamiento extremo como el que el mercado ha construido durante los \u00faltimos a\u00f1os.<\/span><\/p>\n<h2><b>Por qu\u00e9 Burry cree que un colapso de Bitcoin contagiar\u00eda a los mercados tradicionales<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Pero <\/span><b>Burry<\/b><span style=\"font-weight: 400\"> no se detiene en el microcosmos cripto. Su advertencia m\u00e1s inquietante apunta al contagio hacia los mercados tradicionales.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Seg\u00fan su an\u00e1lisis, una <a href=\"https:\/\/www.businessinsider.com\/big-short-michael-burry-bitcoin-price-prediction-consequences-2026-2\" target=\"_blank\" rel=\"noopener\">debacle<\/a> de <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> no quedar\u00eda confinada a los exchanges descentralizados ni a los monederos digitales de los entusiastas. Obligar\u00edan a grandes inversores institucionales a liquidar posiciones ganadoras en <a href=\"https:\/\/crypto-economy.com\/es\/el-oro-y-la-plata-impulsan-la-creciente-demanda-de-perpetuos-de-tradfi-en-los-principales-exchanges-de-criptomonedas\/\" target=\"_blank\" rel=\"noopener\">activos refugio<\/a> como el <\/span><b>oro<\/b><span style=\"font-weight: 400\"> y la <\/span><b>plata<\/b><span style=\"font-weight: 400\"> para cubrir p\u00e9rdidas en criptomonedas.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Estima que hasta <\/span><b>1.000 millones de d\u00f3lares en metales preciosos<\/b><span style=\"font-weight: 400\"> podr\u00edan salir al mercado en una venta forzosa de p\u00e1nico. Esto destruye, de un plumazo, la narrativa de <\/span><b>Bitcoin como cobertura descorrelacionada<\/b><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Si en un momento de estr\u00e9s sist\u00e9mico arrastra a los refugios tradicionales, entonces no solo no ser\u00eda un activo seguro, sino un acelerante de la crisis.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Y el contexto geopol\u00edtico actual \u2014con el <\/span><b>petr\u00f3leo por encima de los 100 d\u00f3lares<\/b><span style=\"font-weight: 400\">, el <a href=\"https:\/\/crypto-economy.com\/es\/bitcoin-cae-por-debajo-de-los-71k\/\" target=\"_blank\" rel=\"noopener\">alto el fuego<\/a> entre <\/span><b>Estados Unidos e Ir\u00e1n<\/b><span style=\"font-weight: 400\"> en \u201csoporte vital\u201d y una relaci\u00f3n cada vez m\u00e1s tensa entre <\/span><b>EE.UU. y China<\/b><span style=\"font-weight: 400\">\u2014 proporciona el escenario perfecto para probar esa hip\u00f3tesis.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Mientras el <\/span><b>oro<\/b><span style=\"font-weight: 400\"> alcanza m\u00e1ximos hist\u00f3ricos, el <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> sigue mostrando una volatilidad impropia de un supuesto dep\u00f3sito de valor. Para <\/span><b>Burry<\/b><span style=\"font-weight: 400\">, esa es la prueba definitiva de su fracaso funcional.<\/span><\/p>\n<h2><b>La burbuja de inteligencia artificial y el riesgo para Bitcoin<\/b><\/h2>\n<p><span style=\"font-weight: 400\">La dimensi\u00f3n m\u00e1s actual de su an\u00e1lisis conecta el destino de <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> con la creciente <\/span><b>burbuja de la inteligencia artificial<\/b><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Estos d\u00edas, <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> volvi\u00f3 a los titulares al asegurar que el <\/span><b>Nasdaq 100<\/b><span style=\"font-weight: 400\"> cotiza a <\/span><b>43 veces ganancias<\/b><span style=\"font-weight: 400\">, niveles que describi\u00f3 como <\/span><i><span style=\"font-weight: 400\">\u201cla escena de un sangriento accidente automovil\u00edstico, minutos antes de que ocurra\u201d.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">La comparaci\u00f3n con la <\/span><b>burbuja puntocom de 1999<\/b><span style=\"font-weight: 400\"> resulta evidente. \u00bfQu\u00e9 tiene esto que ver con <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\">? Todo, si asumimos que los mercados de riesgo se mueven cada vez m\u00e1s al un\u00edsono, alimentados por la misma liquidez y el mismo apetito especulativo.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Un desplome en la tecnolog\u00eda podr\u00eda desencadenar una huida generalizada de activos de riesgo y pondr\u00eda a prueba la resistencia del reciente rebote de <\/span><b>Bitcoin hasta los 82.000 d\u00f3lares<\/b><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La historia reciente ya ofrece pistas: cuando el <\/span><a href=\"https:\/\/crypto-economy.com\/es\/banco-de-japon-para-probar-blockchain\/\" target=\"_blank\" rel=\"noopener\"><b>Banco de Jap\u00f3n<\/b><\/a><span style=\"font-weight: 400\"> subi\u00f3 los tipos al <\/span><b>0,75%<\/b><span style=\"font-weight: 400\"> a principios de 2026, la liquidez global se contrajo y <\/span><b>Bitcoin cay\u00f3 un 25%<\/b><span style=\"font-weight: 400\"> junto a otros activos.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La correlaci\u00f3n no es una teor\u00eda conspirativa. Es un hecho observado que cualquier gestor de riesgos deber\u00eda considerar.<\/span><\/p>\n<h2><b>Strategy, el apalancamiento y la fragilidad del ecosistema cripto<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Llegados a este punto, cabe preguntarse si <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> es un visionario o simplemente un profeta del desastre.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Hay que reconocer que se ha equivocado antes: en 2021 recomend\u00f3 vender acciones antes de un desplome que tard\u00f3 m\u00e1s en llegar, y sus posiciones bajistas contra <\/span><b>Tesla<\/b><span style=\"font-weight: 400\"> le costaron cr\u00edticas feroces.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sin embargo, equivocarse en el timing no invalida el diagn\u00f3stico estructural. Y el an\u00e1lisis de <\/span><b>Burry<\/b><span style=\"font-weight: 400\"> sobre <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> poco a poco deja de parecer una excentricidad para convertirse en un aut\u00e9ntico test de estr\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La dependencia de empresas como <\/span><a href=\"https:\/\/crypto-economy.com\/es\/strategy-refuerza-su-reserva-con-una-nueva-compra-de-bitcoin-de-43m\/\" target=\"_blank\" rel=\"noopener\"><b>Strategy<\/b><\/a><span style=\"font-weight: 400\">, que ya acumula m\u00e1s de <\/span><b>818.000 BTC<\/b><span style=\"font-weight: 400\">, crea un riesgo de concentraci\u00f3n que en cualquier otro mercado activar\u00eda alarmas regulatorias.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El lanzamiento de futuros de volatilidad sobre <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> por parte de <\/span><b>CME Group<\/b><span style=\"font-weight: 400\">, que muchos interpretan como una se\u00f1al de madurez institucional, tambi\u00e9n puede verse desde la \u00f3ptica de Burry como otro mecanismo para maquillar el riesgo sist\u00e9mico y atraer inversores con promesas de cobertura que podr\u00edan fallar durante una tormenta perfecta.<\/span><\/p>\n<h2><b>Las lecciones que deja Michael Burry sobre Bitcoin<\/b><\/h2>\n<p><span style=\"font-weight: 400\">No hace falta compartir el nihilismo de <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> para extraer lecciones valiosas de su an\u00e1lisis.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La primera lecci\u00f3n es evidente: <\/span><b>ning\u00fan activo que aspire a ser reserva de valor puede multiplicarse por mil en una d\u00e9cada y esperar comportarse como una moneda estable y madura.<\/b><\/p>\n<p><span style=\"font-weight: 400\">La segunda es que el apalancamiento oculto y la complejidad de los productos financieros vinculados a <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> han creado una fragilidad que recuerda peligrosamente a las <\/span><b>hipotecas subprime<\/b><span style=\"font-weight: 400\"> antes de 2008.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/\/wp-content\/uploads\/2026\/01\/Michael_Saylor_Bitcoin_Strategy.jpg\" alt=\"Saylor Reaffirms Commitment to Bitcoin Strategy\" \/><\/p>\n<p><span style=\"font-weight: 400\">Capas y capas de ingenier\u00eda financiera funcionan mientras la m\u00fasica sigue sonando, pero colapsan violentamente cuando desaparece la liquidez.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La tercera ense\u00f1anza, quiz\u00e1 la m\u00e1s inc\u00f3moda, es que los grandes evangelizadores de <\/span><b>Bitcoin<\/b><span style=\"font-weight: 400\"> \u2014con <\/span><b>Michael Saylor<\/b><span style=\"font-weight: 400\"> a la cabeza\u2014 se han convertido en actores sist\u00e9micamente importantes cuyo riesgo afecta a accionistas, ETF y mercados enteros.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cuando alguien que se defin\u00eda como <\/span><i><span style=\"font-weight: 400\">\u201cnunca vendedor neto\u201d<\/span><\/i><span style=\"font-weight: 400\"> empieza a admitir que vender\u00eda parte de sus holdings para pagar dividendos, confirma algo inc\u00f3modo: los principios ideol\u00f3gicos se doblan cuando las obligaciones financieras aprietan.<\/span><\/p>\n<h2><b>Bitcoin, miedo y el precio de ignorar el riesgo<\/b><\/h2>\n<p><span style=\"font-weight: 400\">Personalmente, creo que ignorar por completo a <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\"> ser\u00eda un acto de soberbia intelectual.<\/span><\/p>\n<p><b>Bitcoin<\/b><span style=\"font-weight: 400\"> no va a desaparecer, y probablemente seguir\u00e1 ofreciendo ciclos de expansi\u00f3n y contracci\u00f3n durante a\u00f1os. Pero la narrativa de que es inmune a las din\u00e1micas de liquidez o de que la descentralizaci\u00f3n lo convierte autom\u00e1ticamente en un activo a prueba de crisis se debilita con cada correcci\u00f3n sincronizada con los \u00edndices burs\u00e1tiles.<\/span><\/p>\n<p><span style=\"font-weight: 400\">La mayor aportaci\u00f3n de <\/span><b>Burry<\/b><span style=\"font-weight: 400\"> al debate no es el alarmismo, sino la metodolog\u00eda. Obliga al mercado a plantear escenarios adversos, calcular exposiciones y preguntarse qu\u00e9 ocurrir\u00eda si esos niveles psicol\u00f3gicos de <\/span><b>70.000<\/b><span style=\"font-weight: 400\">, <\/span><b>60.000<\/b><span style=\"font-weight: 400\"> o <\/span><b>50.000 d\u00f3lares<\/b><span style=\"font-weight: 400\"> realmente se rompen.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En un mercado dominado por el pensamiento m\u00e1gico y los memes de <\/span><i><span style=\"font-weight: 400\">\u201ca la luna\u201d<\/span><\/i><span style=\"font-weight: 400\">, una dosis de escepticismo radical sigue siendo necesaria.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Porque, como suele recordar <\/span><b>Michael Burry<\/b><span style=\"font-weight: 400\">, las mayores tragedias financieras rara vez ocurren cuando todo el mundo es pesimista. Ocurren cuando el optimismo se convierte en dogma.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Y hoy, mientras <\/span><b>Bitcoin baila alrededor de los 82.000 d\u00f3lares<\/b><span style=\"font-weight: 400\"> y los br\u00f3kers venden futuros de volatilidad como si el riesgo pudiera cubrirse eternamente, la pregunta inc\u00f3moda sigue flotando en el aire:<\/span><\/p>\n<p><b>\u00bfY si el accidente que teme Burry no fuera imposible, sino simplemente prematuro?<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando el legendario inversor Michael Burry habla, el mercado escucha; no porque siempre acierte, sino porque su historial obliga a cualquier persona seria a, como m\u00ednimo, tomar nota. El hombre que vio la crisis de las hipotecas subprime cuando el resto del mundo bailaba sobre una monta\u00f1a de deuda basura, y que fue inmortalizado por &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"La sombra de Burry: Por qu\u00e9 el profeta m\u00e1s temido del mercado sigue viendo a Bitcoin como el gran desastre anunciado\" class=\"read-more button\" href=\"https:\/\/crypto-economy.com\/es\/la-sombra-de-burry-por-que-el-profeta-mas-temido-del-mercado-sigue-viendo-a-bitcoin-como-el-gran-desastre-anunciado\/#more-152978\" aria-label=\"Leer m\u00e1s sobre La sombra de Burry: Por qu\u00e9 el profeta m\u00e1s temido del mercado sigue viendo a Bitcoin como el gran desastre anunciado\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":53,"featured_media":152980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"rank_math_title":"","rank_math_description":"","footnotes":""},"categories":[925],"tags":[8217,4683,6015],"class_list":["post-152978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","tag-debacle-de-bitcoin","tag-mercado","tag-michael-burry"],"_links":{"self":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/152978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/comments?post=152978"}],"version-history":[{"count":1,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/152978\/revisions"}],"predecessor-version":[{"id":152981,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/posts\/152978\/revisions\/152981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/media\/152980"}],"wp:attachment":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/media?parent=152978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/categories?post=152978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/tags?post=152978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}