{"id":56196,"date":"2016-11-29T00:00:00","date_gmt":"2016-11-29T00:00:00","guid":{"rendered":""},"modified":"2023-11-14T09:11:13","modified_gmt":"2023-11-14T09:11:13","slug":"calculadora-mineria-cryptodivisas","status":"publish","type":"page","link":"https:\/\/crypto-economy.com\/es\/calculadora-mineria-cryptodivisas\/","title":{"rendered":"Calculadora de miner\u00eda para criptomonedas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"56196\" class=\"elementor elementor-56196\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a28d16e e-con-full e-flex e-con e-parent\" data-id=\"a28d16e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6b17ded e-flex e-con-boxed e-con e-child\" data-id=\"6b17ded\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5347e63 e-con-full e-flex e-con e-child\" data-id=\"5347e63\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8306b69 elementor-widget elementor-widget-text-editor\" data-id=\"8306b69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><!-- wp:heading --><\/p>\n<p><!-- \/wp:heading --><!-- wp:paragraph --><\/p>\n<p>Si est\u00e1s interesado en <a href=\"https:\/\/crypto-economy.com\/es\/minar-monero\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>minar criptomonedas<\/strong><\/a> o ya est\u00e1s practicando la miner\u00eda, es esencial tener un control de los gastos y beneficios que nos reporta esta pr\u00e1ctica.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Para ello desde Crypto-Economy hemos creado esta calculadora de miner\u00eda para criptomonedas que no debe faltar en tus favoritos.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>Calculadora de miner\u00eda para criptomonedas,<\/strong> calcula los costes y beneficios que te aporta el<strong> minado de criptomonedas<\/strong> al d\u00eda, semana, mes o a\u00f1o.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p>Adem\u00e1s podr\u00e1s comparar que beneficio podr\u00eda darte si minas otra criptomoneda, tan solo necesitas introducir tu Tasa de Hash, la potencia que consumen tus equipos y el precio del Kw\/h en tu pa\u00eds.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>\n<p><strong>Saca el mayor partido a la miner\u00eda de criptomonedas con esta aplicaci\u00f3n.<\/strong><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:shortcode --><\/p>\n<p><!-- \/wp:shortcode --><!-- wp:paragraph {\"align\":\"center\"} --><\/p>\n<p class=\"has-text-align-center\">\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bcfa67 elementor-widget elementor-widget-shortcode\" data-id=\"9bcfa67\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n<html>\r\n<header>\r\n\r\n<script type=\"text\/javascript\">\r\nfunction mostrarPestana(n){\r\n\t\tvar pestanas = document.getElementsByClassName(\"pestana\");\r\n\t\tvar cabecera = document.getElementsByClassName(\"cabecera\");\r\n\t\tfor(i = 0; i<pestanas.length; i++){\r\n\t\t\tif(pestanas[i].className.includes(\"p-activa\")){\r\n\t\t\t\tpestanas[i].className = pestanas[i].className.replace(\"p-activa\", \"\");\r\n\t\t\t\tcabecera[i].className = cabecera[i].className.replace(\"c-activa\", \"\");\r\n\t\t\t\tbreak;\r\n\t\t\t}\r\n\t\t}\r\n\t\tpestanas[n].className += \" p-activa\";\r\n\t\tcabecera[n].className += \" c-activa\";\r\n\t}\r\n\r\nwindow.onload=function(){\r\nvar pos=window.name || 0;\r\nwindow.scrollTo(0,pos);\r\n}\r\nwindow.onunload=function(){\r\nwindow.name=self.pageYOffset || (document.documentElement.scrollTop+document.body.scrollTop);\r\n}\r\n\r\n\r\n\r\nfunction nFormatter(num, digits) {\r\n  var si = [\r\n \/\/   { value: 1E18, symbol: \" E\" },\r\n \/\/   { value: 1E15, symbol: \" P\" },\r\n\/\/    { value: 1E12, symbol: \" T\" },\r\n    { value: 1E9,  symbol: \" B\" },\r\n    { value: 1E6,  symbol: \" M\" },\r\n    { value: 1E3,  symbol: \" k\" }\r\n  ], rx = \/\\.0+$|(\\.[0-9]*[1-9])0+$\/, i;\r\n  for (i = 0; i < si.length; i++) {\r\n    if (num >= si[i].value) {\r\n      return (num \/ si[i].value).toFixed(digits).replace(rx, \"$1\") + si[i].symbol;\r\n    }\r\n  }\r\n  return num.toFixed(digits).replace(rx, \"$1\");\r\n}\r\n\r\n\r\n\r\nfunction calculator(coin){\r\n\t\t\t\r\n\t\t\/\/ (B21-(B5*B6))-(B21*B4)\r\n\t\t\/\/ (block_time\/(My_hash_rate\/Net_hash))\/3600  = tiempo en horas para encontrar un bloque\r\n\t\t\r\n\t\t\/\/VALORES A TRAVES DE PHP, SI SE A\u00d1ADE UNA NUEVA HAY QUE A\u00d1ADIR AQUI LA MONEDA Y PASAR LOS VALORES AL SCRYPT\r\n\t\tif (coin==\"zcash\"){\r\n\t\t\t\r\n\t\t\t\r\n\t\t\tvar net_hash=parseFloat(15608528067) , block_time=parseFloat(76.0) , coins_per_block=parseFloat(1.25), coin_price=parseFloat(0.0072447501600284), price_btc=parseFloat(81022.2);\r\n\t\t\t\r\n\t\t}\r\n\t\telse if (coin==\"ethereum\" ){\r\n\t\tvar net_hash=parseFloat(1639421505966) , block_time=parseFloat(12.9793) , coins_per_block=parseFloat(2.0013223358617), coin_price=parseFloat(4.0033334785426E-6), price_btc=parseFloat(81022.2);\r\n\t\t\r\n\t\t}\r\n\t\telse if (coin==\"ethclassic\"){\r\n\t\tvar net_hash=parseFloat(200437779234421) , block_time=parseFloat(13.3742) , coins_per_block=parseFloat(1.98656), coin_price=parseFloat(0.0001167433252374), price_btc=parseFloat(81022.2);\r\n\t\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"decred\"){\r\n\t\tvar net_hash=parseFloat() , block_time=parseFloat() , coins_per_block=parseFloat(), coin_price=parseFloat(), price_btc=parseFloat(81022.2);\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"monero\"){\r\n\t\tvar net_hash=parseFloat(5310236554) , block_time=parseFloat(126.0) , coins_per_block=parseFloat(0.60093978), coin_price=parseFloat(0.0051055142911449), price_btc=parseFloat(81022.2);\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"btc\"){\r\n\t\tvar net_hash=parseFloat(9.0025784053763E+20) , block_time=parseFloat(632.0) , coins_per_block=parseFloat(3.147866635), coin_price=parseInt(1) , price_btc=parseFloat(81022.2);\t\r\n\t\t\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"beam\"){\r\n\t\tvar net_hash=parseFloat(160512) , block_time=parseFloat(60.0) , coins_per_block=parseFloat(25), coin_price=parseFloat() , price_btc=parseFloat(81022.2);\t\r\n\t\t\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"komodo\"){\r\n\t\tvar net_hash=parseFloat(148636) , block_time=parseFloat(60.0) , coins_per_block=parseFloat(1), coin_price=parseFloat(0), price_btc=parseFloat(81022.2);\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"Grin-CT32\"){\r\n\t\tvar net_hash=parseFloat(8304) , block_time=parseFloat(61.0) , coins_per_block=parseFloat(60), coin_price=parseFloat(3.8712876455574E-7), price_btc=parseFloat(81022.2);\r\n\t\t\r\n\t\t}\r\n\t\t\r\n\t\telse if (coin==\"luxcoin\"){\r\n\t\tvar net_hash=parseFloat(0) , block_time=parseFloat(60) , coins_per_block=parseFloat(10), coin_price=parseFloat(), price_btc=parseFloat(81022.2);\r\n\t\t\r\n\t\t}\r\n\t\t\r\n\t\telse {\r\n\t\tvar net_hash=45140279 , block_time=150 , coins_per_block=10, coin_price=0.07, price_btc=1200;\t\r\n\t\t\t\r\n\t\t}\r\n\r\n\t\/\/\t$btc[\"block_time\"]\r\n\t\/\/\talert (net_hash);\r\n\t\/\/\talert (block_time);\r\n\t\/\/\talert (coins_per_block);\r\n\t\/\/\talert (coin_price);\r\n\t\/\/\talert (price_btc);\r\n\t\tvar my_hash_rate=0;\r\n\t\tvar power=0;\r\n\t\tvar cost_kw=0;\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\tif (document.getElementById(\"hash_selector_\"+coin).value == \"Kh\/s\"){\r\n\t\t\t my_hash_rate=parseFloat(document.getElementById(\"hash_rate_\"+coin).value)*1000;\r\n\t\t\r\n\t\t} \r\n\t\telse if(document.getElementById(\"hash_selector_\"+coin).value == \"Mh\/s\"){\r\n\t\t\t my_hash_rate=parseFloat(document.getElementById(\"hash_rate_\"+coin).value)*1000000;\t\r\n\t\t}\r\n\t\telse if(document.getElementById(\"hash_selector_\"+coin).value == \"Gh\/s\"){\r\n\t\t\t my_hash_rate=parseFloat(document.getElementById(\"hash_rate_\"+coin).value)*1000000000;\t\r\n\t\t}\r\n\t\telse if(document.getElementById(\"hash_selector_\"+coin).value == \"Th\/s\"){\r\n\t\t\t my_hash_rate=parseFloat(document.getElementById(\"hash_rate_\"+coin).value)*1000000000000;\t\r\n\t\t}\t\t\r\n\t\telse{\t\r\n\t\t\t my_hash_rate=parseFloat(document.getElementById(\"hash_rate_\"+coin).value);\r\n\t\t}\r\n\t\t\r\n\t\t\r\n\t\t\r\n\t\t power=parseFloat(document.getElementById(\"power_\"+coin).value)\/1000;\r\n\t\t\r\n\t\t cost_kw=parseFloat(document.getElementById(\"cost_kw_\"+coin).value);\r\n\t\t\r\n\t\t\t\t\r\n\t\tvar second_found_block =(block_time\/(my_hash_rate\/net_hash)); \r\n\t\t\r\n\r\n\t\t\r\n\t\r\n\t\tvar coins_year_found = 1\/(((block_time\/(my_hash_rate\/net_hash))\/31536000)\/coins_per_block);\r\n\t\t\r\n\t\tvar coins_btc_year =coins_year_found*coin_price;\r\n\t\t\r\n\t\tvar coins_power_year =((cost_kw*power)*24)*365;\r\n\t\r\n\t\tvar coins_profit_year =((coins_year_found*coin_price)*price_btc)-(coins_power_year);\r\n\t\r\n\t\r\n\t\r\n\t\r\n\t\r\n\t\t\r\n\tif (!isNaN(my_hash_rate)&&!isNaN(power)&&!isNaN(cost_kw) ){\r\n\t\t\/\/dia\r\n\t\tdocument.getElementById(coin+\"_day\").innerHTML =Math.round((coins_year_found\/365)*100)\/100;\r\n\t\tdocument.getElementById(coin+\"_btc_day\").innerHTML =Math.round((coins_btc_year\/365)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_power_day\").innerHTML =\"$ \"+Math.round((coins_power_year\/365)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_profit_day\").innerHTML =\"$ \"+nFormatter(Math.round(((coins_profit_year\/365)*100)\/(100)),2);\r\n\t\t\/\/semana\r\n\t\tdocument.getElementById(coin+\"_week\").innerHTML =Math.round((coins_year_found\/52.143)*100)\/100;\r\n\t\tdocument.getElementById(coin+\"_btc_week\").innerHTML =Math.round((coins_btc_year\/52.143)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_power_week\").innerHTML =\"$ \"+Math.round((coins_power_year\/52.143)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_profit_week\").innerHTML =\"$ \"+nFormatter(Math.round(((coins_profit_year\/52.143)*100)\/(100)),2);\r\n\t\t\/\/mes\r\n\t\tdocument.getElementById(coin+\"_month\").innerHTML =Math.round((coins_year_found\/12)*100)\/100;\r\n\t\tdocument.getElementById(coin+\"_btc_month\").innerHTML =Math.round((coins_btc_year\/12)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_power_month\").innerHTML =\"$ \"+Math.round((coins_power_year\/12)*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_profit_month\").innerHTML =\"$ \"+nFormatter(Math.round(((coins_profit_year\/12)*100)\/(100)),2);\r\n\t\t\/\/a\u00f1o\r\n\t\tdocument.getElementById(coin+\"_year\").innerHTML =Math.round(coins_year_found*100)\/100;\r\n\t\tdocument.getElementById(coin+\"_btc_year\").innerHTML =Math.round(coins_btc_year*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_power_year\").innerHTML =\"$ \"+Math.round(coins_power_year*1000)\/1000;\r\n\t\tdocument.getElementById(coin+\"_profit_year\").innerHTML =\"$ \"+nFormatter(Math.round((coins_profit_year*100)\/(100)),2);\r\n\t\r\n\t}\r\n\t\r\n\t\t\r\n\t}\r\n\r\n\r\n\r\n<\/script>\r\n<\/header>\r\n\r\n<body>\r\n\r\n\r\n\r\n<div name=\"ancha\" class=\"contenedor\">\r\n\r\n\t<a href=\"#ancla\" class=\"cabecera c-activa\" onclick=\"mostrarPestana(0);\">ZEC<\/a>\r\n\t<div class=\"pestana p-activa\">\r\n\t\t\t\t\r\n\t<div class=\"calculator\">\r\n  \t\t<div class=\"calculator-izq\">\r\n\t\t\t<div class=\"panelcalculator\">\r\n       \t\t\t<div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/zec-2.jpg\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n       \t\t  <\/div>\r\n          \r\n         \t\t <div class=\"name_calculator\">ZCASH\r\n         \t\t <\/div>\r\n          \t\t <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div  class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <form>\r\n                        <input id=\"hash_rate_zcash\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" placeholder=\"1000\" onkeyup=\"calculator('zcash')\" onChange=\"calculator('zcash')\" maxlength=\"10\">\r\n                         <select id=\"hash_selector_zcash\" class=\"hash_selector\" onkeyup=\"calculator('zcash')\" onChange=\"calculator('zcash')\">\r\n                        <option label=\"h\/s\" value=\"h\/s\" selected=\"selected\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                                               \r\n                        <\/select>\r\n                        <\/form>\r\n                    <\/div>\r\n                   \r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_zcash\" class=\"input_calculator\" type=\"text\" name=\"power\" placeholder=\"200\" onkeyup=\"calculator('zcash')\" onChange=\"calculator('zcash')\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_zcash\" class=\"input_calculator\" type=\"text\" placeholder=\"0.15\" onkeyup=\"calculator('zcash')\" onChange=\"calculator('zcash')\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    \r\n                    \r\n                  \r\n                    \r\n         \t<\/div>\r\n     \t <\/div>\t\r\n  \t <\/div>\r\n  \r\n      <div class=\"dch_calculator\">\r\n        <div class=\"stats_calculator\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Tiempo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">1.27 min                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Net Hash\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">15608.53 Kh\/s                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Precio\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0.007245                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"market_cap\">$ 9.786.515.398                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n        <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">1.25                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">144805680.31                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">3340484                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algoritmo\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">Equihash                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n        \r\n        <div class=\"resultados_calculator\">\r\n            <div class=\"label_tiempo\"> Dia\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Beneficio\r\n                <\/div>\r\n                 <div id=\"zcash_profit_day\" class=\"profit_result\">\r\n                 <\/div>\r\n                \r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">BTC\r\n                <\/div>\r\n                <div id=\"zcash_btc_day\" class=\"profit_result\" maxlength=\"5\" >\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">ZEC\r\n                <\/div>\r\n                <div id=\"zcash_day\" class=\"profit_result\" maxlength=\"5\" >\r\n                <\/div>\r\n            <\/div>\t\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Coste el\u00e9ctrico\r\n                <\/div>\r\n                <div id=\"zcash_power_day\" class=\"profit_result\" maxlength=\"5\" >\r\n                <\/div>\r\n            <\/div>\t\t\r\n        <\/div>\r\n        <div class=\"resultados_calculator\">\r\n                <div class=\"label_tiempo\"> Semana\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Beneficio\r\n                <\/div>\r\n                <div id=\"zcash_profit_week\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">BTC\r\n                <\/div>\r\n                <div id=\"zcash_btc_week\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">ZEC\r\n                <\/div>\r\n                <div id=\"zcash_week\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Coste el\u00e9ctrico\r\n                <\/div>\r\n                <div id=\"zcash_power_week\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t \t\r\n        <\/div>\r\n        <div class=\"resultados_calculator\">\r\n                <div class=\"label_tiempo\"> Mes\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Beneficio\r\n                <\/div>\r\n                <div id=\"zcash_profit_month\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">BTC\r\n                <\/div>\r\n                <div id=\"zcash_btc_month\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">ZEC\r\n                <\/div>\r\n                <div id=\"zcash_month\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Coste el\u00e9ctrico\r\n                <\/div>\r\n                <div id=\"zcash_power_month\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t\t\r\n        <\/div>\r\n        <div class=\"resultados_calculator\">\r\n                <div class=\"label_tiempo\"> A\u00f1o\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Beneficio\r\n                <\/div>\r\n                <div id=\"zcash_profit_year\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">BTC\r\n                <\/div>\r\n                <div id=\"zcash_btc_year\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">ZEC\r\n                <\/div>\r\n                <div id=\"zcash_year\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t\r\n            <div class=\"label_result\">\t\r\n                <div class=\"profit_label\">Coste el\u00e9ctrico\r\n                <\/div>\r\n                <div id=\"zcash_power_year\" class=\"profit_result\">\r\n                <\/div>\r\n            <\/div>\t\t\r\n        <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\t\r\n                    \r\n                  \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div>\r\n\t\t\t\r\n            \r\n \t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(1);\">ETH POW<\/a>\r\n\t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/coins\/ethpow_calc.webp\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Ethereum POW\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_ethereum\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('ethereum')\" onChange=\"calculator('ethereum')\" placeholder=\"1000\" maxlength=\"10\">\r\n                         <select id=\"hash_selector_ethereum\" class=\"hash_selector\" onkeyup=\"calculator('ethereum')\" onChange=\"calculator('ethereum')\">\r\n                        <option label=\"h\/s\" value=\"h\/s\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        <option label=\"Mh\/s\" value=\"Mh\/s\" selected=\"selected\">Mh\/s<\/option>\r\n                        <option label=\"Gh\/s\" value=\"Gh\/s\">Gh\/s<\/option>\r\n                        <option label=\"Th\/s\" value=\"Th\/s\">Th\/s<\/option>\r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_ethereum\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('ethereum')\" onChange=\"calculator('ethereum')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_ethereum\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('ethereum')\" onChange=\"calculator('ethereum')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">12.98 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">1.64 Th\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 4.0E-6            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 34.976.483            <\/div>\t\r\n    \t<\/div>\r\n    <\/div>\r\n     <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">2                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">21278543552386                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">24235703                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algoritmo\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algoritym\">Equihash                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n    \t\r\n    \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethereum_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethereum_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH\r\n            <\/div>\r\n            <div id=\"ethereum_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethereum_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethereum_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethereum_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH\r\n            <\/div>\r\n            <div id=\"ethereum_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethereum_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethereum_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethereum_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH\r\n            <\/div>\r\n            <div id=\"ethereum_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethereum_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethereum_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethereum_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH\r\n            <\/div>\r\n            <div id=\"ethereum_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethereum_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div>\r\n    \r\n                    \r\n                    \r\n                    \r\n                        \r\n                    \r\n              \r\n                \r\n            \r\n\t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(2);\">ETC<\/a>\r\n   <div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"><img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/etc-2.jpg\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">ETH Classic\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_ethclassic\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('ethclassic')\" onChange=\"calculator('ethclassic')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_ethclassic\" class=\"hash_selector\" onkeyup=\"calculator('ethclassic')\" onChange=\"calculator('ethclassic')\">\r\n                        <option label=\"h\/s\" value=\"h\/s\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        <option label=\"Mh\/s\" value=\"Mh\/s\" selected=\"selected\">Mh\/s<\/option>\r\n                        <option label=\"Gh\/s\" value=\"Gh\/s\">Gh\/s<\/option>\r\n                        <option label=\"Th\/s\" value=\"Th\/s\">Th\/s<\/option>\r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_ethclassic\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('ethclassic')\" onChange=\"calculator('ethclassic')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_ethclassic\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('ethclassic')\" onChange=\"calculator('ethclassic')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">13.37 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">200.44 Th\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0.000117            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 1.482.134.140            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n    \r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">1.99                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">2.680694947037E+15                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">24549089                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algoritmo\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">Etchash                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethclassic_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethclassic_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH Classic\r\n            <\/div>\r\n            <div id=\"ethclassic_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethclassic_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethclassic_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethclassic_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH Classic\r\n            <\/div>\r\n            <div id=\"ethclassic_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethclassic_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethclassic_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethclassic_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH Classic\r\n            <\/div>\r\n            <div id=\"ethclassic_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethclassic_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"ethclassic_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"ethclassic_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">ETH Classic\r\n            <\/div>\r\n            <div id=\"ethclassic_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"ethclassic_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div>\r\n\t\t\t\r\n            \r\n\t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(3);\">DCR<\/a>\r\n\t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\">  <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/decred-coin.png\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Decred\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_decred\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('decred')\" onChange=\"calculator('decred')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_decred\" class=\"hash_selector\" onkeyup=\"calculator('decred')\" onChange=\"calculator('decred')\">\r\n                        <option label=\"h\/s\" value=\"h\/s\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        <option label=\"Mh\/s\" value=\"Mh\/s\" selected=\"selected\" >Mh\/s<\/option>\r\n                        <option label=\"Gh\/s\" value=\"Gh\/s\">Gh\/s<\/option>\r\n                        <option label=\"Th\/s\" value=\"Th\/s\">Th\/s<\/option>\r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_decred\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('decred')\" onChange=\"calculator('decred')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_decred\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('decred')\" onChange=\"calculator('decred')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">0 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">0 Th\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 0            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n    \r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">0                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">0                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">0                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algoritmo\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"decred_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"decred_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">DCR\r\n            <\/div>\r\n            <div id=\"decred_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"decred_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"decred_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"decred_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">DCR\r\n            <\/div>\r\n            <div id=\"decred_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"decred_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"decred_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"decred_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">DCR\r\n            <\/div>\r\n            <div id=\"decred_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"decred_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"decred_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"decred_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">DCR\r\n            <\/div>\r\n            <div id=\"decred_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"decred_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div>\r\n  \r\n  \r\n \r\n\t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(4);\">XMR<\/a>\r\n \t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/xmr-3.jpg\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Monero\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_monero\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('monero')\" onChange=\"calculator('monero')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_monero\" class=\"hash_selector\" onkeyup=\"calculator('monero')\" onChange=\"calculator('monero')\">\r\n                        <option label=\"h\/s\" value=\"h\/s\" selected=\"selected\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        <option label=\"Mh\/s\" value=\"Mh\/s\" >Mh\/s<\/option>\r\n                        <option label=\"Gh\/s\" value=\"Gh\/s\">Gh\/s<\/option>\r\n                        <option label=\"Th\/s\" value=\"Th\/s\">Th\/s<\/option>\r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_monero\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('monero')\" onChange=\"calculator('monero')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_monero\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('monero')\" onChange=\"calculator('monero')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">126 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">5310.24 Kh\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0.005106            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 7.630.680.153            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n    \r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">0.6                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">669089805815                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">3672824                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algorithm\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">RandomX                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"monero_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"monero_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">XMR\r\n            <\/div>\r\n            <div id=\"monero_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"monero_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"monero_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"monero_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">XMR\r\n            <\/div>\r\n            <div id=\"monero_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"monero_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"monero_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"monero_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">XMR\r\n            <\/div>\r\n            <div id=\"monero_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"monero_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"monero_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"monero_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">XMR\r\n            <\/div>\r\n            <div id=\"monero_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"monero_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div>\r\n    \r\n \r\n\t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(5);\">BTC<\/a>\r\n \t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/btc-13.jpg\" alt=\"Zcash_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Bitcoin\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_btc\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('btc')\" onChange=\"calculator('btc')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_btc\" class=\"hash_selector\" onkeyup=\"calculator('btc')\" onChange=\"calculator('btc')\">\r\n                        <option label=\"Gh\/s\" value=\"Gh\/s\">Gh\/s<\/option>\r\n                        <option label=\"Th\/s\" value=\"Th\/s\" selected=\"selected\">Th\/s<\/option>\r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_btc\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('btc')\" onChange=\"calculator('btc')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_btc\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('btc')\" onChange=\"calculator('btc')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">10.533333333333 min            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">900257.84 Ph\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">$ 81022.2            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 1.622.757 M            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">3.15                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">1.3247201107903E+14                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">949162                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algorithm\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">SHA-256                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"btc_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"btc_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"btc_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"btc_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"btc_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"btc_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"btc_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"btc_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n \t<\/div> \r\n\t<\/div>\r\n <\/div>\r\n  \r\n  \t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(6);\">KMD<\/a>\r\n \t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/komodo_calculator-2.jpg\" alt=\"Komodo_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Komodo\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_komodo\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('komodo')\" onChange=\"calculator('komodo')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_komodo\" class=\"hash_selector\" onkeyup=\"calculator('komodo')\" onChange=\"calculator('komodo')\">\r\n                        \r\n                        <option label=\"h\/s\" value=\"h\/s\" selected=\"selected\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        \r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_komodo\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('komodo')\" onChange=\"calculator('komodo')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_komodo\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('komodo')\" onChange=\"calculator('komodo')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">60 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">0.15 Kh\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 0            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n    \r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">3\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">557388.66                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">4927335                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Rentabilidad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"market_cap\">%\r\n                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"komodo_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"komodo_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">KMD\r\n            <\/div>\r\n            <div id=\"komodo_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"komodo_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"komodo_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"komodo_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">KMD\r\n            <\/div>\r\n            <div id=\"komodo_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"komodo_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"komodo_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"komodo_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">KMD\r\n            <\/div>\r\n            <div id=\"komodo_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"komodo_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"komodo_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"komodo_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">KMD\r\n            <\/div>\r\n            <div id=\"komodo_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"komodo_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div> \r\n  \r\n  \r\n  \t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(7);\">BEAM<\/a>\r\n \t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/beam-coin.png\" alt=\"Beam_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Beam\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_beam\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('beam')\" onChange=\"calculator('beam')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_beam\" class=\"hash_selector\" onkeyup=\"calculator('beam')\" onChange=\"calculator('beam')\">\r\n                        \r\n                        <option label=\"h\/s\" value=\"h\/s\" selected=\"selected\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\" >Kh\/s<\/option>\r\n                        \r\n                        \r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_beam\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('beam')\" onChange=\"calculator('beam')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_beam\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('beam')\" onChange=\"calculator('beam')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n  <div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">60 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">0.16 Kh\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 0            <\/div>\t\r\n    \t<\/div>\r\n    \t\r\n    <\/div>\r\n    \r\n         <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">100                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">9630743                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">3858044                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Rentabilidad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"market_cap\">%\r\n                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n        \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"beam_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"beam_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beam\r\n            <\/div>\r\n            <div id=\"beam_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"beam_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"beam_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"beam_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beam\r\n            <\/div>\r\n            <div id=\"beam_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"beam_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"beam_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"beam_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beam\r\n            <\/div>\r\n            <div id=\"beam_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"beam_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"beam_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"beam_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beam\r\n            <\/div>\r\n            <div id=\"beam_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"beam_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n   \r\n \r\n  \r\n <\/div> \r\n<\/div>\r\n\r\n                    \r\n                    \r\n                    \r\n                    \r\n\t\t\t\t\r\n  <\/div> \r\n  \r\n  \r\n  \r\n    \r\n  \r\n  \r\n     \t<a href=\"#ancla\" class=\"cabecera\" onclick=\"mostrarPestana(8);\">GRIN<\/a>\r\n \t<div class=\"pestana\">\r\n\t\t\t\t\r\n\t\t\t\t\t\r\n <div class=\"calculator\">\r\n  <div class=\"calculator-izq\">\r\n\t\t<div class=\"panelcalculator\">\r\n          <div class=\"img_calculator\"> <img decoding=\"async\" src=\"https:\/\/crypto-economy.com\/wp-content\/uploads\/2019\/07\/grin-coin.png\" alt=\"Grin_calculator\" style=\"margin:10px 60px;\" >\r\n          <\/div>\r\n          <div class=\"name_calculator\">Grin\r\n          <\/div>\r\n           <div class=\"variables_calculator\">\r\n          \t\t\t\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Tasa de Hash\r\n                        <\/div>\r\n                        <input id=\"hash_rate_grin\" class=\"input_calculator_hash\" type=\"text\" name=\"hash_rate\" onkeyup=\"calculator('grin')\" onChange=\"calculator('grin')\" placeholder=\"1000\" maxlength=\"10\">\r\n                        <select id=\"hash_selector_grin\" class=\"hash_selector\" onkeyup=\"calculator('grin')\" onChange=\"calculator('grin')\">\r\n                        \r\n                         <option label=\"h\/s\" value=\"h\/s\" selected=\"selected\">h\/s<\/option>\r\n                        <option label=\"Kh\/s\" value=\"Kh\/s\">Kh\/s<\/option>\r\n                        \r\n                        <\/select>\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Potencia (W)\r\n                        <\/div>\r\n                        <input id=\"power_grin\" class=\"input_calculator\" type=\"text\" name=\"power\" onkeyup=\"calculator('grin')\" onChange=\"calculator('grin')\" placeholder=\"200\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                    <div class=\"form_calculator\">\r\n                    \t<div class=\"label_panel_calculator\"> Coste KW\/h ($)\r\n                        <\/div>\r\n                        <input id=\"cost_kw_grin\" class=\"input_calculator\" type=\"text\" name=\"costkw\" onkeyup=\"calculator('grin')\" onChange=\"calculator('grin')\" placeholder=\"0.15\" maxlength=\"10\" value=\"0\">\r\n                    <\/div>\r\n                   \r\n                    \r\n                    \r\n                    \r\n         \r\n   \t \t  <\/div>\r\n       \r\n         \r\n        \r\n         \r\n          \r\n        <\/div>\t\r\n  <\/div>\r\n  \r\n<div class=\"dch_calculator\">\r\n  \t<div class=\"stats_calculator\">\r\n    \t<div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Tiempo Bloque\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"block_time\">61 sec            <\/div>\r\n        <\/div>\r\n    \t<div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Net Hash\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"difficulty\">8.3 Kh\/s            <\/div>\r\n    \t<\/div>\r\n        <div class=\"blocks_calculator\" >\r\n        \t<div class=\"label_blocks\"> Precio\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"exchange_rate\">\u0243 0.00000039            <\/div>   \r\n               \t<\/div>\r\n        <div class=\"blocks_calculator\">\r\n        \t<div class=\"label_blocks\"> Capitalizaci\u00f3n\r\n            <\/div>\r\n            <div class=\"result_blocks\" id=\"market_cap\">$ 7.227.743            <\/div>\t\r\n    \t<\/div>\r\n    <\/div>\r\n     <div class=\"stats_calculator2\">\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Block Reward\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"block_time\">60                <\/div>  \r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Dificultad\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"difficulty\">506565.06                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\" >\r\n                <div class=\"label_blocks\"> Ultimo Bloque\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"exchange_rate\">3840252                <\/div>\r\n            <\/div>\r\n            <div class=\"blocks_calculator\">\r\n                <div class=\"label_blocks\"> Algoritmo\r\n                <\/div>\r\n                <div class=\"result_blocks\" id=\"algorithm\">Cuckatoo32                <\/div>\t\r\n            <\/div>\r\n            \r\n        <\/div>\r\n    \t\r\n    \r\n    <div class=\"resultados_calculator\">\r\n    \t<div class=\"label_tiempo\"> Dia\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"grin_profit_day\" class=\"profit_result\"><\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"grin_btc_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">GRIN\r\n            <\/div>\r\n            <div id=\"grin_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"grin_power_day\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n   \t\t\t<div class=\"label_tiempo\"> Semana\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"grin_profit_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"grin_btc_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">GRIN\r\n            <\/div>\r\n            <div id=\"grin_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"grin_power_week\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t \t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> Mes\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"grin_profit_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"grin_btc_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">GRIN\r\n            <\/div>\r\n            <div id=\"grin_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"grin_power_month\" class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n    <div class=\"resultados_calculator\">\r\n    \t\t<div class=\"label_tiempo\"> A\u00f1o\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Beneficio\r\n            <\/div>\r\n            <div id=\"grin_profit_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">BTC\r\n            <\/div>\r\n            <div id=\"grin_btc_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">GRIN\r\n            <\/div>\r\n            <div id=\"grin_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\r\n        <div class=\"label_result\">\t\r\n        \t<div class=\"profit_label\">Coste el\u00e9ctrico\r\n            <\/div>\r\n            <div id=\"grin_power_year\"  class=\"profit_result\">\r\n            <\/div>\r\n        <\/div>\t\t\r\n    <\/div>\r\n <\/div> \r\n<\/div>\t\t\r\n  <\/div> \r\n<\/div>\r\n<\/body>\r\n<\/html>\r\n\r\n\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5875889 elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"5875889\" data-element_type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:80,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"container\" data-elementor-id=\"72305\" class=\"elementor elementor-72305\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d3d6d e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"b2d3d6d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b05277a elementor-widget elementor-widget-heading\" data-id=\"b05277a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><p class=\"elementor-heading-title elementor-size-default\">Ads<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70de3fd elementor-widget elementor-widget-html\" data-id=\"70de3fd\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div style=\"width:300px;height:250px\">\r\n    <div class=\"sevioads\" data-zone=\"a3fb4454-4825-49c1-aa46-1f5f22eefb0f\"><\/div>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fdbe4a elementor-widget elementor-widget-spacer\" data-id=\"8fdbe4a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79671dc elementor-hidden-mobile e-con-full elementor-hidden-tablet e-flex e-con e-child\" data-id=\"79671dc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48f32a62 elementor-widget elementor-widget-heading\" data-id=\"48f32a62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">S\u00edguenos en Redes<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48544112 elementor-shape-rounded elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"48544112\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-57b1d67\" href=\"https:\/\/www.facebook.com\/CryptoEconomyES\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-x-twitter elementor-repeater-item-a8689cc\" href=\"https:\/\/x.com\/CryptoEconomyEN\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">X-twitter<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-x-twitter\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-telegram elementor-repeater-item-1fe3e4c\" href=\"https:\/\/t.me\/CryptoEconomyESP\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Telegram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-telegram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-repeater-item-307b815\" href=\"https:\/\/www.tiktok.com\/@cryptoeconomynews\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-tiktok\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-de4d432\" href=\"https:\/\/www.linkedin.com\/in\/crypto-economy\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab3a261 elementor-widget elementor-widget-heading\" data-id=\"ab3a261\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cripto Tutoriales<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e008bb elementor-widget elementor-widget-image\" data-id=\"5e008bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMKu1lQswvJmrAw?hl=es-419&#038;gl=US&#038;ceid=US%3Aes-419\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"82\" src=\"https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2023\/11\/Follow-Google-News-300x82.png\" class=\"attachment-medium size-medium wp-image-87505\" alt=\"Follow Google News\" srcset=\"https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2023\/11\/Follow-Google-News-300x82.png 300w, https:\/\/crypto-economy.com\/es\/\/wp-content\/uploads\/sites\/4\/2023\/11\/Follow-Google-News.png 468w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ce6da5 e-grid e-con-boxed e-con e-child\" data-id=\"2ce6da5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85cdcd4 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"85cdcd4\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/aprende-sobre-criptomonedas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutoriales (Nivel B\u00e1sico)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95da5e9 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"95da5e9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/cripto-tutoriales-nivel-medio\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutoriales (Nivel Medio)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c51c774 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c51c774\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/cripto-tutoriales-nivel-avanzado\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutoriales (Nivel Avanzado)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb69879 elementor-widget elementor-widget-heading\" data-id=\"bb69879\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Cripto Reviews<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-065576b e-grid e-con-boxed e-con e-child\" data-id=\"065576b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-457d7ca elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"457d7ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/listado-wallets-de-criptomonedas\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wallets Cripto<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ee90a3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5ee90a3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/listado-de-exchanges-cripto-cex-y-dex\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cripto Exchanges (CEX\/DEX)<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9053ca elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"d9053ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/criptomonedas-de-la-a-a-la-d\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Criptos A - D<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a18fbf5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"a18fbf5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/criptomonedas-de-la-e-a-la-n\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Criptos E - N<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a73986 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4a73986\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/crypto-economy.com\/es\/criptomonedas-de-la-o-a-la-z\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Criptos O - Z<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Si est\u00e1s interesado en minar criptomonedas o ya est\u00e1s practicando la miner\u00eda, es esencial tener un control de los gastos y beneficios que nos reporta esta pr\u00e1ctica. Para ello desde Crypto-Economy hemos creado esta calculadora de miner\u00eda para criptomonedas que no debe faltar en tus favoritos. Calculadora de miner\u00eda para criptomonedas, calcula los costes y &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Calculadora de miner\u00eda para criptomonedas\" class=\"read-more button\" href=\"https:\/\/crypto-economy.com\/es\/calculadora-mineria-cryptodivisas\/#more-56196\" aria-label=\"Leer m\u00e1s sobre Calculadora de miner\u00eda para criptomonedas\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-56196","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/pages\/56196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/comments?post=56196"}],"version-history":[{"count":0,"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/pages\/56196\/revisions"}],"wp:attachment":[{"href":"https:\/\/crypto-economy.com\/es\/wp-json\/wp\/v2\/media?parent=56196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}